{"id":2965,"date":"2019-08-23T11:36:42","date_gmt":"2019-08-23T11:36:42","guid":{"rendered":"https:\/\/www.artsmusica.net\/cursos\/?post_type=artsmusica_cursos&#038;p=2965"},"modified":"2021-09-26T09:14:07","modified_gmt":"2021-09-26T07:14:07","slug":"7-evaluacion-final","status":"publish","type":"artsmusica_cursos","link":"https:\/\/www.artsmusica.net\/cursos\/curso\/de-rossini-a-wagner-la-opera-del-romanticismo\/7-evaluacion-final\/","title":{"rendered":"7. Evaluaci\u00f3n final"},"content":{"rendered":"\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\" data-block-type=\"core\"><\/div>\n\n\n\n<p>Hemos llegado al final de este curso de historia de la m\u00fasica: \u00ab<strong>De Rossini a Wagner: la \u00f3pera del Romanticismo<\/strong>\u00ab. Si ya has terminado de estudiar todas las lecciones puedes proceder a realizar la evaluaci\u00f3n final (para alumnos de nivel plus y premium).<\/p>\n\n\n\n<p>La prueba consiste en contestar el siguiente cuestionario eligiendo la respuesta correcta. Se trata de preguntas tipo test que se refieren a los contenidos que hemos estudiado.<\/p>\n\n\n\n<p>Una vez finalices el cuestionario, autom\u00e1ticamente te aparecer\u00e1n las respuestas correctas y los errores (si los hubieran). Tambi\u00e9n recibir\u00e1s un email con tus resultados. Si tu nota fuera aprobatoria (m\u00e1s de 5 sobre 10), recibir\u00e1s el&nbsp;<strong>certificado de finalizaci\u00f3n del curso<\/strong>&nbsp;en tu email en un plazo de 48 horas. Si tienes dudas o no recibes el certificado en el plazo estimado, escribe un email a&nbsp;<a rel=\"noreferrer noopener\" href=\"mailto:direccion@artsmusica.net\" target=\"_blank\">direccion@artsmusica.net<\/a>.<\/p>\n\n\n\n<p>Si no apruebas no te preocupes, puedes prepararte de nuevo y presentar el cuestionario nuevamente. \u00a1Suerte!<\/p>\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\" data-block-type=\"core\"><\/div>\n\n\n\n<hr class=\"wp-block-separator\"\/ data-block-type=\"core\">\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\" data-block-type=\"core\"><\/div>\n\n\n\n<h2 class=\"has-text-align-center wp-block-heading\" data-block-type=\"core\">Cuestionario<\/h2>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\" data-block-type=\"core\"><\/div>\n\n\n<p data-block-type=\"core\"><div class=\"rcp_restricted\"><p><!-- wp:paragraph {\"backgroundColor\":\"very-light-gray\"} --><\/p>\n<p class=\"has-background has-very-light-gray-background-color\"><i class=\"fas fa-lock\"> <\/i> Este contenido est\u00e1 \u00fanicamente disponible para los suscriptores. Puedes <a href=\"#login\"> identificarte aqu\u00ed<\/a> , <a href=\"https:\/\/www.artsmusica.net\/cursos\/niveles-de-suscripcion\/\"> suscribirte<\/a> o <a href=\"https:\/\/www.artsmusica.net\/cursos\/registro\/\">actualizar tu nivel de suscripci\u00f3n<\/a>.<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<\/div><\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\" data-block-type=\"core\"><\/div>\n\n\n\n<h2 class=\"has-text-align-center wp-block-heading\" data-block-type=\"core\">Lecciones del curso<\/h2>\n\n\n\n<p class=\"indice has-very-light-gray-background-color has-background\"><strong><a href=\"https:\/\/www.artsmusica.net\/cursos\/curso\/de-rossini-a-wagner-la-opera-del-romanticismo\/1-la-opera-belcantista-rossini-donizetti-y-bellini\/\">Lecci\u00f3n 1. La \u00f3pera belcantista: Rossini, Donizetti y Bellini<\/a><\/strong><\/p>\n\n\n\n<p class=\"indice has-very-light-gray-background-color has-background\"><strong><a href=\"https:\/\/www.artsmusica.net\/cursos\/curso\/de-rossini-a-wagner-la-opera-del-romanticismo\/2-la-opera-de-verdi-y-el-verismo-de-mascagni-leoncavallo-y-puccini\/\">Lecci\u00f3n 2. La \u00f3pera de Verdi y el verismo de Mascagni, Leoncavallo y Puccini<\/a><\/strong><\/p>\n\n\n\n<p class=\"indice has-very-light-gray-background-color has-background\"><strong><a href=\"https:\/\/www.artsmusica.net\/cursos\/curso\/de-rossini-a-wagner-la-opera-del-romanticismo\/3-el-primer-romanticismo-aleman-schubert-y-weber\/\">Lecci\u00f3n 3. El primer Romanticismo alem\u00e1n: Schubert y Weber<\/a><\/strong><\/p>\n\n\n\n<p class=\"indice has-very-light-gray-background-color has-background\"><strong><a href=\"https:\/\/www.artsmusica.net\/cursos\/curso\/de-rossini-a-wagner-la-opera-del-romanticismo\/4-el-drama-musical-de-wagner\/\">Lecci\u00f3n 4. El drama musical de Wagner<\/a><\/strong><\/p>\n\n\n\n<p class=\"indice has-very-light-gray-background-color has-background\"><strong><a href=\"https:\/\/www.artsmusica.net\/cursos\/curso\/de-rossini-a-wagner-la-opera-del-romanticismo\/5-la-gran-opera-de-meyerbeer\/\">Lecci\u00f3n 5. La \u201cgran \u00f3pera\u201d de Meyerbeer<\/a><\/strong><\/p>\n\n\n\n<p class=\"indice has-very-light-gray-background-color has-background\"><strong><a href=\"https:\/\/www.artsmusica.net\/cursos\/curso\/de-rossini-a-wagner-la-opera-del-romanticismo\/6-la-opera-lirica-y-otras-tendencias\/\">Lecci\u00f3n 6. La \u00f3pera l\u00edrica y otras tendencias<\/a><\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center indice-destacado has-background\" style=\"background-color:#ffffff\"><strong><a href=\"https:\/\/www.artsmusica.net\/cursos\/curso\/de-rossini-a-wagner-la-opera-del-romanticismo\/7-evaluacion-final\/\">Evaluaci\u00f3n final<\/a><\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center\"><strong><a href=\"https:\/\/www.artsmusica.net\/cursos\/apreciacion-musical\/de-rossini-a-wagner-la-opera-del-romanticismo\/\">Regresar a la p\u00e1gina principal del curso<\/a><\/strong><\/p>\n","protected":false},"featured_media":0,"parent":509,"menu_order":7,"template":"","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"class_list":{"0":"post-2965","1":"artsmusica_cursos","2":"type-artsmusica_cursos","3":"status-publish","5":"entry"},"featured_image_urls_v2":{"full":"","thumbnail":"","medium":"","medium_large":"","large":"","1536x1536":"","2048x2048":"","sidebar-featured":"","genesis-singular-images":"","gb-block-post-grid-landscape":"","gb-block-post-grid-square":""},"post_excerpt_stackable_v2":"<p>Hemos llegado al final de este curso de historia de la m\u00fasica: \u00abDe Rossini a Wagner: la \u00f3pera del Romanticismo\u00ab. Si ya has terminado de estudiar todas las lecciones puedes proceder a realizar la evaluaci\u00f3n final (para alumnos de nivel plus y premium). La prueba consiste en contestar el siguiente cuestionario eligiendo la respuesta correcta. Se trata de preguntas tipo test que se refieren a los contenidos que hemos estudiado. Una vez finalices el cuestionario, autom\u00e1ticamente te aparecer\u00e1n las respuestas correctas y los errores (si los hubieran). Tambi\u00e9n recibir\u00e1s un email con tus resultados. Si tu nota fuera aprobatoria (m\u00e1s&hellip;<\/p>\n","category_list_v2":"","author_info_v2":{"name":"","url":""},"comments_num_v2":"0 comentarios","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.artsmusica.net\/cursos\/wp-json\/wp\/v2\/artsmusica_cursos\/2965","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.artsmusica.net\/cursos\/wp-json\/wp\/v2\/artsmusica_cursos"}],"about":[{"href":"https:\/\/www.artsmusica.net\/cursos\/wp-json\/wp\/v2\/types\/artsmusica_cursos"}],"version-history":[{"count":7,"href":"https:\/\/www.artsmusica.net\/cursos\/wp-json\/wp\/v2\/artsmusica_cursos\/2965\/revisions"}],"predecessor-version":[{"id":16534,"href":"https:\/\/www.artsmusica.net\/cursos\/wp-json\/wp\/v2\/artsmusica_cursos\/2965\/revisions\/16534"}],"up":[{"embeddable":true,"href":"https:\/\/www.artsmusica.net\/cursos\/wp-json\/wp\/v2\/artsmusica_cursos\/509"}],"wp:attachment":[{"href":"https:\/\/www.artsmusica.net\/cursos\/wp-json\/wp\/v2\/media?parent=2965"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}